{"id":3,"date":"2023-05-30T16:54:16","date_gmt":"2023-05-30T16:54:16","guid":{"rendered":"https:\/\/buildremco.ca\/?page_id=3"},"modified":"2023-11-09T15:35:30","modified_gmt":"2023-11-09T15:35:30","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/buildremco.ca\/fr\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a93693 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0a93693\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b87a69e\" data-id=\"b87a69e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-605f7da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"605f7da\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8b14a8a\" data-id=\"8b14a8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c387a05 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget__width-initial elementor-widget elementor-widget-divider\" data-id=\"c387a05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-c387a05{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7e9ab1 elementor-widget elementor-widget-heading\" data-id=\"c7e9ab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-c7e9ab1{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-589b836 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget__width-initial elementor-widget elementor-widget-divider\" data-id=\"589b836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tconfidentialit\u00e9\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3b72f5 elementor-widget elementor-widget-heading\" data-id=\"f3b72f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9 <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81cd690 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"81cd690\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5a1e623\" data-id=\"5a1e623\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b038bad elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"b038bad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1367\" src=\"https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/11\/s-3.jpg\" class=\"attachment-full size-full wp-image-424\" alt=\"\" srcset=\"https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/11\/s-3.jpg 2048w, https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/11\/s-3-300x200.jpg 300w, https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/11\/s-3-1024x684.jpg 1024w, https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/11\/s-3-768x513.jpg 768w, https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/11\/s-3-1536x1025.jpg 1536w, https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/11\/s-3-18x12.jpg 18w, https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/11\/s-3-1200x801.jpg 1200w, https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/11\/s-3-1400x934.jpg 1400w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3edafd3 elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"3edafd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"600\" src=\"https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/06\/Rectangle-35-2.png\" class=\"attachment-full size-full wp-image-360\" alt=\"\" srcset=\"https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/06\/Rectangle-35-2.png 750w, https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/06\/Rectangle-35-2-300x240.png 300w, https:\/\/buildremco.ca\/wp-content\/uploads\/2023\/06\/Rectangle-35-2-15x12.png 15w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fade614 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fade614\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2ec4cf\" data-id=\"d2ec4cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2851fd9 elementor-widget elementor-widget-text-editor\" data-id=\"2851fd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span style=\"color: #003366;\"><span class=\"TextRun SCXW22873359 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW22873359 BCX8\" data-ccp-parastyle=\"heading 1\">Politique de confidentialit\u00e9<\/span><\/span><span class=\"EOP SCXW22873359 BCX8\" data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/span><\/h1><p><strong><span style=\"color: #003366;\">Remco Construcci\u00f3n Inc.<\/span><\/strong><\/p><p><span style=\"color: #003366;\"><strong><span lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\">Derni\u00e8re mise \u00e0 jour : <\/span><span lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\">23\/06\/2023<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/strong><\/span><\/p><p><span data-contrast=\"auto\">Veuillez lire attentivement cette Politique de confidentialit\u00e9 avant d&#8217;utiliser Notre Service. Les informations suivantes sont divulgu\u00e9es par <\/span><span data-contrast=\"auto\">Remco Construction Inc<\/span><span data-contrast=\"auto\"> \u00e0 Votre \u00e9gard conform\u00e9ment \u00e0 la loi de Nouveau-Brunswick du Canada.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Ce Site Web est exploit\u00e9 par <\/span><span data-contrast=\"auto\">Remco Construction Inc<\/span><span data-contrast=\"auto\">. Tout au long du pr\u00e9sent Service (\u00ab https:\/\/www.remcogroup.ca \u00bb), les termes \u00ab Nous \u00bb, \u00ab Notre \u00bb et \u00ab Nos \u00bb font r\u00e9f\u00e9rence \u00e0 <\/span><span data-contrast=\"auto\">Remco Construction Inc<\/span><span data-contrast=\"auto\">. Cette Politique de confidentialit\u00e9 d\u00e9crit nos politiques et proc\u00e9dures en mati\u00e8re de collecte, d&#8217;utilisation et de divulgation de vos informations lorsque Vous utilisez ce Service, ainsi que vos droits \u00e0 la vie priv\u00e9e et comment la loi Vous prot\u00e8ge.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous utilisons vos Donn\u00e9es personnelles pour fournir et am\u00e9liorer le Service. En utilisant le Service, Vous acceptez la collecte et l&#8217;utilisation d&#8217;informations conform\u00e9ment \u00e0 la pr\u00e9sente Politique de confidentialit\u00e9.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d0143c elementor-widget elementor-widget-heading\" data-id=\"9d0143c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Interpr\u00e9tation and D\u00e9finitions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f28672d elementor-widget elementor-widget-text-editor\" data-id=\"f28672d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Interpr\u00e9tation<\/h3><p><span class=\"TextRun SCXW234571056 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW234571056 BCX8\" data-ccp-parastyle=\"heading 4\">Les mots dont la premi\u00e8re lettre est en majuscule ont des significations d\u00e9finies dans les conditions suivantes. Les d\u00e9finitions suivantes auront la m\u00eame signification ind\u00e9pendamment de leur forme au singulier ou au pluriel.<\/span><\/span><span class=\"EOP SCXW234571056 BCX8\" data-ccp-props=\"{&quot;134245418&quot;:false,&quot;134245529&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><h3><strong>D\u00e9finitions<\/strong><\/h3><p><span class=\"TextRun SCXW198436333 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW198436333 BCX8\">Aux fins de cette Politique de confidentialit\u00e9 :<\/span><\/span><span class=\"EOP SCXW198436333 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW230544607 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230544607 BCX8\">Compte<\/span><\/span><\/strong><span class=\"TextRun SCXW230544607 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW230544607 BCX8\"> d\u00e9signe un compte unique cr\u00e9\u00e9 pour Vous permettre d&#8217;acc\u00e9der \u00e0 notre service ou \u00e0 certaines parties de notre service.<\/span><\/span><span class=\"EOP SCXW230544607 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Entreprise<\/span><\/b><span data-contrast=\"auto\"> (d\u00e9sign\u00e9e par les termes <\/span><span data-contrast=\"auto\">\u00ab<\/span> <span data-contrast=\"auto\">l&#8217;Entreprise \u00bb, <\/span><span data-contrast=\"auto\">\u00ab <\/span><span data-contrast=\"auto\">Nous \u00bb, <\/span><span data-contrast=\"auto\">\u00ab <\/span><span data-contrast=\"auto\">Notre \u00bb ou <\/span><span data-contrast=\"auto\">\u00ab <\/span><span data-contrast=\"auto\">Nos \u00bb dans cette Politique) d\u00e9signe <\/span><span data-contrast=\"auto\">Remco Construction Inc<\/span><span data-contrast=\"auto\">, Sh\u00e9diac, NB Canada.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW77065846 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW77065846 BCX8\">Cookies<\/span><\/span><\/strong><span class=\"TextRun SCXW77065846 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW77065846 BCX8\"> d\u00e9signe de petits fichiers qui sont plac\u00e9s sur Votre ordinateur, Votre appareil mobile ou tout autre appareil par un site Web, contenant les d\u00e9tails de Votre historique de navigation sur ce Site Web parmi ses nombreuses utilisations. Cela permet \u00e0 Votre exp\u00e9rience utilisateur d&#8217;\u00eatre adapt\u00e9e \u00e0 Vos pr\u00e9f\u00e9rences, et Nous permet de fournir et d&#8217;am\u00e9liorer le service.<\/span><\/span><span class=\"EOP SCXW77065846 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW70089600 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW70089600 BCX8\">Pays<\/span><\/span><\/strong><span class=\"TextRun SCXW70089600 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW70089600 BCX8\"> d\u00e9signe <\/span><span class=\"NormalTextRun SCXW70089600 BCX8\">Nouveau-Brunswick,<\/span> <span class=\"NormalTextRun SCXW70089600 BCX8\">Canada<\/span><\/span><span class=\"EOP SCXW70089600 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW163475054 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW163475054 BCX8\">Appareil<\/span><\/span><\/strong><span class=\"TextRun SCXW163475054 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW163475054 BCX8\"> d\u00e9signe tout appareil capable d&#8217;acc\u00e9der au Service, tel qu&#8217;un ordinateur, un t\u00e9l\u00e9phone portable ou une tablette num\u00e9rique, sans limitation.<\/span><\/span><span class=\"EOP SCXW163475054 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW96773749 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW96773749 BCX8\">Donn\u00e9es personnelles<\/span><\/span><\/strong><span class=\"TextRun SCXW96773749 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW96773749 BCX8\"> d\u00e9signent toute information qui se rapporte \u00e0 une personne physique identifi\u00e9e ou identifiable.<\/span><\/span><span class=\"EOP SCXW96773749 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW186179777 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW186179777 BCX8\">Le, Ce et\/ou Notre Service<\/span><\/span><\/strong><span class=\"TextRun SCXW186179777 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW186179777 BCX8\"> d\u00e9signe le Site Web.<\/span><\/span><span class=\"EOP SCXW186179777 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW222132029 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW222132029 BCX8\">Fournisseurs de services<\/span><\/span><\/strong><span class=\"TextRun SCXW222132029 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW222132029 BCX8\"> d\u00e9signent les personnes physiques ou morales qui traitent les donn\u00e9es pour le compte de l&#8217;Entreprise. Ce terme fait r\u00e9f\u00e9rence \u00e0 des entreprises ou des individus tiers employ\u00e9s par l&#8217;Entreprise pour faciliter le Service, fournir le Service au nom de l&#8217;Entreprise, effectuer des services li\u00e9s au Service ou aider l&#8217;Entreprise \u00e0 analyser comment le Service est utilis\u00e9 (par exemple, l&#8217;entreprise d&#8217;h\u00e9bergement qui Nous permet d&#8217;offrir le Service).<\/span><\/span><span class=\"EOP SCXW222132029 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Service de m\u00e9dias sociaux tiers<\/span><\/b><span data-contrast=\"auto\"> d\u00e9signe tout site Web ou tout site de r\u00e9seau social \u00e0 travers lequel un utilisateur peut se connecter ou cr\u00e9er un compte pour utiliser le Service.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW20968491 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW20968491 BCX8\">Donn\u00e9es d&#8217;utilisation<\/span><\/span><\/strong><span class=\"TextRun SCXW20968491 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW20968491 BCX8\"> d\u00e9signe les donn\u00e9es collect\u00e9es automatiquement, g\u00e9n\u00e9r\u00e9es soit par l&#8217;utilisation du Service, soit par l&#8217;infrastructure du Service lui-m\u00eame (par exemple, la dur\u00e9e d&#8217;une visite de page).<\/span><\/span><span class=\"EOP SCXW20968491 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW182013964 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW182013964 BCX8\">Site Web <\/span><\/span><\/strong><span class=\"TextRun SCXW182013964 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW182013964 BCX8\">d\u00e9signe<\/span><span class=\"NormalTextRun SCXW182013964 BCX8\"> [<\/span><\/span><span class=\"TextRun SCXW182013964 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW182013964 BCX8\">Remco Construction Inc<\/span><\/span><span class=\"TextRun SCXW182013964 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW182013964 BCX8\">, accessible depuis https:\/\/www.<\/span><span class=\"NormalTextRun SCXW182013964 BCX8\">remcogroup.ca<\/span><\/span><span class=\"EOP SCXW182013964 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun SCXW113080584 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW113080584 BCX8\">Vous, Votre et\/ou Vous-m\u00eame<\/span><\/span><\/strong><span class=\"TextRun SCXW113080584 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW113080584 BCX8\"> d\u00e9signe l&#8217;individu acc\u00e9dant ou utilisant le Service, ou la soci\u00e9t\u00e9 ou autre entit\u00e9 juridique au nom de laquelle cet individu acc\u00e8de ou utilise le Service, le cas \u00e9ch\u00e9ant.<\/span><\/span><span class=\"EOP SCXW113080584 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d0c545 elementor-widget elementor-widget-heading\" data-id=\"9d0c545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Collecte et Utilisation de vos Donn\u00e9es Personnelles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04ceba6 elementor-widget elementor-widget-heading\" data-id=\"04ceba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Types de donn\u00e9es collect\u00e9es <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4588195 elementor-widget elementor-widget-text-editor\" data-id=\"4588195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span class=\"TextRun SCXW120288376 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW120288376 BCX8\" data-ccp-parastyle=\"heading 5\">Donn\u00e9es personnelles<\/span><\/span><span class=\"EOP SCXW120288376 BCX8\" data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:80,&quot;335559740&quot;:276}\">\u00a0<\/span><\/h3><p><span class=\"TextRun SCXW88083539 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW88083539 BCX8\">Lorsque Vous utilisez notre service, Nous pouvons Vous demander de Nous fournir certaines informations personnelles identifiables qui peuvent \u00eatre utilis\u00e9es pour Vous contacter ou Vous identifier. Les informations personnelles identifiables peuvent inclure, sans toutefois s&#8217;y limiter :<\/span><\/span><span class=\"EOP SCXW88083539 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><ul><li><span class=\"TextRun SCXW251928310 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW251928310 BCX8\">Adresse e-mail<\/span><\/span><span class=\"EOP SCXW251928310 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span class=\"TextRun SCXW244306801 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW244306801 BCX8\">Pr\u00e9nom et nom de famille<\/span><\/span><span class=\"EOP SCXW244306801 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span class=\"TextRun SCXW196281343 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW196281343 BCX8\">Num\u00e9ro de t\u00e9l\u00e9phone<\/span><\/span><span class=\"EOP SCXW196281343 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span class=\"TextRun SCXW217109657 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW217109657 BCX8\">Adresse, \u00c9tat, Province, Code postal, Ville<\/span><\/span><span class=\"EOP SCXW217109657 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span class=\"TextRun SCXW192260029 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW192260029 BCX8\">Donn\u00e9es d\u2019utilisation<\/span><\/span><span class=\"EOP SCXW192260029 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ul><h3><strong><span class=\"TextRun SCXW123444138 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW123444138 BCX8\" data-ccp-parastyle=\"heading 5\">Donn\u00e9es d&#8217;utilisation<\/span><\/span><\/strong><\/h3><p><span class=\"TextRun SCXW216726277 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW216726277 BCX8\">Les Donn\u00e9es d&#8217;utilisation sont collect\u00e9es automatiquement lors de l&#8217;utilisation du Service.<\/span><\/span><span class=\"EOP SCXW216726277 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW115227515 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW115227515 BCX8\">Les Donn\u00e9es d&#8217;utilisation peuvent inclure des informations telles que l&#8217;adresse de protocole Internet de Votre Appareil (par exemple, adresse IP), le type de navigateur, la version du navigateur, les pages de notre service que Vous visitez, l&#8217;heure et la date de Votre visite, le temps pass\u00e9 sur ces pages, des identifiants d&#8217;appareils uniques et d&#8217;autres donn\u00e9es de diagnostic.<\/span><\/span><span class=\"EOP SCXW115227515 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW105087971 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW105087971 BCX8\">Lorsque Vous acc\u00e9dez au Service via un appareil mobile, Nous pouvons collecter certaines informations automatiquement, y compris, mais sans s&#8217;y limiter, le type d&#8217;appareil mobile que Vous utilisez, l&#8217;identifiant unique de Votre appareil mobile, l&#8217;adresse IP de Votre appareil mobile, Votre syst\u00e8me d&#8217;exploitation mobile, le type de navigateur Internet mobile que Vous utilisez, des identifiants d&#8217;appareils uniques et d&#8217;autres donn\u00e9es de diagnostic.<\/span><\/span><\/p><p><span class=\"TextRun SCXW97417992 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW97417992 BCX8\">Nous pouvons \u00e9galement collecter des informations que Votre navigateur envoie chaque fois que Vous visitez notre Service ou lorsque Vous acc\u00e9dez au Service via un appareil mobile.<\/span><\/span><span class=\"EOP SCXW97417992 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><h3><span class=\"TextRun SCXW189330067 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW189330067 BCX8\" data-ccp-parastyle=\"heading 5\">Informations provenant de services de m\u00e9dias sociaux tiers<\/span><\/span><span class=\"EOP SCXW189330067 BCX8\" data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:80,&quot;335559740&quot;:276}\">\u00a0<\/span><\/h3><p><span class=\"TextRun SCXW100623705 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW100623705 BCX8\">L&#8217;Entreprise Vous permet de cr\u00e9er un Compte et de Vous connecter pour utiliser le service via les services de m\u00e9dias sociaux tiers suivants :<\/span><\/span><span class=\"EOP SCXW100623705 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><ul><li>Google<\/li><li>Facebook<\/li><\/ul><p><span class=\"TextRun SCXW16184344 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW16184344 BCX8\">Si Vous d\u00e9cidez de Vous inscrire ou de Nous accorder autrement l&#8217;acc\u00e8s \u00e0 un Service de m\u00e9dias sociaux tiers, Nous pouvons collecter des donn\u00e9es personnelles qui sont d\u00e9j\u00e0 associ\u00e9es \u00e0 Votre Compte de Service de m\u00e9dias sociaux tiers, telles que Votre nom, Votre adresse e-mail, Vos activit\u00e9s ou Votre liste de contacts associ\u00e9e \u00e0 ce Compte.<\/span><\/span><span class=\"EOP SCXW16184344 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW155997593 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW155997593 BCX8\">Vous pouvez \u00e9galement avoir la possibilit\u00e9 de partager des informations suppl\u00e9mentaires avec l&#8217;entreprise via Votre Compte de Service de m\u00e9dias sociaux tiers. Si Vous choisissez de fournir de telles informations et des donn\u00e9es personnelles, lors de l&#8217;inscription ou autrement, Vous donnez \u00e0 l&#8217;entreprise la permission de les utiliser, de les partager et de les stocker conform\u00e9ment \u00e0 cette Politique de confidentialit\u00e9.<\/span><\/span><span class=\"EOP SCXW155997593 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><h3><span class=\"TextRun SCXW24369502 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW24369502 BCX8\" data-ccp-parastyle=\"heading 5\">Technologies de suivi et Cookies<\/span><\/span><span class=\"EOP SCXW24369502 BCX8\" data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:80,&quot;335559740&quot;:276}\">\u00a0<\/span><\/h3><p><span data-contrast=\"auto\">Nous utilisons des Cookies et des technologies de suivi similaires pour suivre l&#8217;activit\u00e9 sur Notre service et stocker certaines informations. Les technologies de suivi utilis\u00e9es sont des balises, des \u00e9tiquettes et des scripts pour collecter et suivre des informations et pour am\u00e9liorer et analyser Notre service. Les technologies que Nous utilisons peuvent inclure :<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW108952929 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW108952929 BCX8\">Cookies ou Cookies de navigateur<\/span><\/span><\/strong><span class=\"TextRun SCXW108952929 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW108952929 BCX8\"><strong>.<\/strong> Un cookie est un petit fichier plac\u00e9 sur Votre Appareil. Vous pouvez demander \u00e0 Votre navigateur de refuser tous les Cookies ou de Vous indiquer quand un cookie est envoy\u00e9. Cependant, si Vous n&#8217;acceptez pas les Cookies, Vous ne pourrez peut-\u00eatre pas utiliser certaines parties de notre service. Sauf si Vous avez modifi\u00e9 les param\u00e8tres de Votre navigateur pour refuser les Cookies, Notre service est en mesure d\u2019utiliser des Cookies.<\/span><\/span><span class=\"EOP SCXW108952929 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW166504791 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW166504791 BCX8\">Cookies Flash.<\/span><\/span><\/strong><span class=\"TextRun SCXW166504791 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW166504791 BCX8\"> Certaines fonctionnalit\u00e9s de Notre service peuvent utiliser des objets stock\u00e9s localement (ou Cookies Flash) pour collecter et stocker des informations sur Vos pr\u00e9f\u00e9rences ou Votre activit\u00e9 sur Notre service. Les Cookies Flash ne sont pas g\u00e9r\u00e9s par les m\u00eames param\u00e8tres de navigateur que ceux utilis\u00e9s pour les Cookies de navigateur. Pour plus d&#8217;informations sur la mani\u00e8re dont Vous pouvez supprimer les Cookies Flash, veuillez lire \u00ab O\u00f9 puis-je modifier les param\u00e8tres pour d\u00e9sactiver ou supprimer les objets partag\u00e9s locaux? \u00bb disponible \u00e0 l&#8217;adresse suivante : https:\/\/helpx.adobe.com\/flash-player\/kb\/disable-local-shared-objects-flash.html#main_Where_can_I_change_the_settings_for_disabling__or_deleting_local_shared_objects_<\/span><\/span><span class=\"EOP SCXW166504791 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong>Web Beacons.<\/strong> Certain sections of Our Service and Our emails may contain small electronic files known as web beacons (also referred to as clear gifs, pixel tags, and single-pixel gifs) that permit the Company, for example, to count users who have visited those pages or opened an email and for other <br \/>related website statistics (for example, recording the popularity of a certain section and verifying system and server integrity). Cookies can be &#8220;Persistent&#8221; or &#8220;Session&#8221; Cookies. Persistent Cookies remain on Your personal computer or mobile device when You go offline, while Session Cookies are deleted as soon as You <br \/>close Your web browser. We use both Session and Persistent Cookies for the purposes set out below:<\/p><p><strong><span class=\"TextRun Underlined SCXW32239723 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW32239723 BCX8\">Balises Web<\/span><\/span><\/strong><span class=\"TextRun SCXW32239723 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><strong><span class=\"NormalTextRun SCXW32239723 BCX8\">.<\/span><\/strong><span class=\"NormalTextRun SCXW32239723 BCX8\"> Certaines sections de Notre service et de Nos e-mails peuvent contenir de petits fichiers \u00e9lectroniques appel\u00e9s balises Web (\u00e9galement appel\u00e9es gifs clairs, balises pixel et gifs d&#8217;un seul pixel) qui permettent \u00e0 l&#8217;Entreprise, par exemple, de compter les utilisateurs qui ont visit\u00e9 ces pages ou ouvert un e-mail et pour d&#8217;autres statistiques li\u00e9es au Site Web (par exemple, enregistrer la popularit\u00e9 d&#8217;une section en particullier et v\u00e9rifier l&#8217;int\u00e9grit\u00e9 du syst\u00e8me et du serveur).<\/span><\/span><span class=\"EOP SCXW32239723 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW258968190 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW258968190 BCX8\">Les Cookies peuvent \u00eatre des Cookies \u00ab persistants \u00bb ou des Cookies de \u00ab session \u00bb. Les Cookies persistants restent sur Votre ordinateur personnel ou Votre appareil mobile lorsque Vous \u00eates hors ligne, tandis que les Cookies de session sont supprim\u00e9s d\u00e8s que Vous fermez Votre navigateur Web.\u00a0<\/span><\/span><span class=\"EOP SCXW258968190 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW7124859 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW7124859 BCX8\">Nous utilisons \u00e0 la fois des Cookies de session et des Cookies persistants aux fins d\u00e9crites ci-dessous :<\/span><\/span><span class=\"EOP SCXW7124859 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong>Cookies n\u00e9cessaires \/ essentiels\u00a0<\/strong><\/p><p><span data-contrast=\"auto\">Type : Cookies de session<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Administr\u00e9s par : Nous<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Objectif : Ces Cookies sont essentiels pour Vous fournir les services disponibles sur le Site Web et Vous permettre d&#8217;utiliser certaines de ses fonctionnalit\u00e9s. Ils aident \u00e0 authentifier les utilisateurs et \u00e0 pr\u00e9venir l&#8217;utilisation frauduleuse des comptes d&#8217;utilisateurs. Sans ces Cookies, les services que Vous avez demand\u00e9s ne peuvent pas \u00eatre fournis. Nous n&#8217;utilisons ces Cookies que pour Vous fournir ces services.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong>Cookies de la Politique en mati\u00e8re de Cookies \/ de suivi de l\u2019acceptation des Cookies\u00a0<\/strong><\/p><p><span data-contrast=\"auto\">Type : Cookies persistants<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Administr\u00e9s par : Nous<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Objectif : Ces Cookies identifient si les utilisateurs ont accept\u00e9 l&#8217;utilisation de cookies sur le Site Web.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong>Cookies de fonctionnalit\u00e9\u00a0<\/strong><\/p><p><span data-contrast=\"auto\">Type : Cookies persistants<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Administr\u00e9s par : Nous<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Objectif : Ces Cookies Nous permettent de m\u00e9moriser les choix que Vous faites lorsque Vous utilisez le Site Web, tels que Vos coordonn\u00e9es de connexion ou Vos pr\u00e9f\u00e9rences linguistiques. Le but de ces Cookies est de Vous fournir une exp\u00e9rience plus personnelle et d&#8217;\u00e9viter que Vous ayez \u00e0 saisir \u00e0 nouveau Vos pr\u00e9f\u00e9rences \u00e0 chaque fois que Vous utilisez le Site Web.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Pour plus d&#8217;informations sur les cookies que Nous utilisons et Vos choix en mati\u00e8re de cookies, veuillez consulter notre Politique de Cookies ou la section Cookies de notre Politique de confidentialit\u00e9.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW120101204 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW120101204 BCX8\">En utilisant le Service, Vous acceptez cette Politique de confidentialit\u00e9.<\/span><\/span><span class=\"EOP SCXW120101204 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8916d1 elementor-widget elementor-widget-heading\" data-id=\"d8916d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'utilisation de vos donn\u00e9es personnelles <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65efab5 elementor-widget elementor-widget-text-editor\" data-id=\"65efab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW67750767 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW67750767 BCX8\">L\u2019Entreprise peut utiliser des Donn\u00e9es personnelles \u00e0 des fins telles que celles mentionn\u00e9es ci-apr\u00e8s :<\/span><\/span><span class=\"EOP SCXW67750767 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong>Fournir et maintenir notre Service<\/strong><span data-contrast=\"auto\">, y compris surveiller l&#8217;utilisation de notre Service.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong>G\u00e9rer Votre Compte<\/strong><span data-contrast=\"auto\"><strong>:<\/strong> pour g\u00e9rer Votre inscription en tant qu&#8217;utilisateur du service. Les donn\u00e9es personnelles que Vous fournissez peuvent Vous donner acc\u00e8s \u00e0 diff\u00e9rentes fonctionnalit\u00e9s du service qui sont disponibles pour Vous en tant qu&#8217;utilisateur enregistr\u00e9.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong>Pour l&#8217;ex\u00e9cution d&#8217;un contrat<\/strong><span data-contrast=\"auto\"><strong> :<\/strong> le d\u00e9veloppement, la conformit\u00e9 et l&#8217;ex\u00e9cution du contrat d&#8217;achat des produits, articles ou services que Vous avez achet\u00e9s ou de tout autre contrat avec Nous via le service.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW39865359 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW39865359 BCX8\">Pour Vous contacter<\/span><\/span><\/strong><span class=\"TextRun SCXW39865359 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW39865359 BCX8\"><strong> :<\/strong> pour Vous contacter par e-mail, appels t\u00e9l\u00e9phoniques, SMS ou d&#8217;autres formes \u00e9quivalentes de communication \u00e9lectronique, telles que des notifications push d&#8217;une application mobile, concernant des mises \u00e0 jour ou des communications informatives li\u00e9es aux fonctionnalit\u00e9s, produits ou services contract\u00e9s, y compris les mises \u00e0 jour de s\u00e9curit\u00e9, lorsque cela est n\u00e9cessaire ou raisonnable pour leur mise en \u0153uvre.<\/span><\/span><span class=\"EOP SCXW39865359 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW71028943 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW71028943 BCX8\">Pour Vous fournir<\/span><\/span><\/strong><span class=\"TextRun SCXW71028943 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW71028943 BCX8\"> des nouvelles, des offres sp\u00e9ciales et des informations g\u00e9n\u00e9rales sur d&#8217;autres biens, services et \u00e9v\u00e9nements que Nous proposons et qui sont similaires \u00e0 ceux que Vous avez d\u00e9j\u00e0 achet\u00e9s ou sur lesquels Vous Vous \u00eates renseign\u00e9, sauf si Vous avez choisi de ne pas recevoir de telles informations.<\/span><\/span><span class=\"EOP SCXW71028943 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW249933963 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW249933963 BCX8\">Pour g\u00e9rer Vos demandes:<\/span><\/span><\/strong><span class=\"TextRun SCXW249933963 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW249933963 BCX8\"> pour r\u00e9pondre et g\u00e9rer Vos demandes \u00e0 Notre \u00e9gard.<\/span><\/span><span class=\"EOP SCXW249933963 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW191409312 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW191409312 BCX8\">Pour les transferts d&#8217;entreprise:<\/span><\/span><\/strong><span class=\"TextRun SCXW191409312 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW191409312 BCX8\"> Nous pouvons utiliser Vos informations pour \u00e9valuer ou effectuer une fusion, une cession d&#8217;actifs, une restructuration, une r\u00e9organisation, une dissolution ou une autre vente ou transfert de tout ou partie de Nos actifs, que ce soit en tant qu&#8217;entreprise en activit\u00e9 ou dans le cadre d&#8217;une proc\u00e9dure de faillite, de liquidation ou de proc\u00e9dure similaire, dans laquelle les donn\u00e9es personnelles d\u00e9tenues par Nous \u00e0 propos des utilisateurs de Notre service font partie des actifs transf\u00e9r\u00e9s.<\/span><\/span><span class=\"EOP SCXW191409312 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW249296817 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW249296817 BCX8\">\u00c0 d&#8217;autres fins:<\/span><\/span><\/strong><span class=\"TextRun SCXW249296817 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW249296817 BCX8\"> Nous pouvons utiliser Vos informations \u00e0 d&#8217;autres fins, telles que l&#8217;analyse de donn\u00e9es, l&#8217;identification des tendances d&#8217;utilisation, la d\u00e9termination de l&#8217;efficacit\u00e9 de Nos campagnes promotionnelles et pour \u00e9valuer et am\u00e9liorer Notre service, Nos produits, Nos services, Notre marketing et Votre exp\u00e9rience.<\/span><\/span><span class=\"EOP SCXW249296817 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span class=\"TextRun SCXW84485908 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW84485908 BCX8\">Nous pouvons partager Vos informations personnelles dans les situations suivantes:<\/span><\/span><span class=\"EOP SCXW84485908 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW264721731 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW264721731 BCX8\">Avec des Fournisseurs de services<\/span><\/span><\/strong><span class=\"TextRun SCXW264721731 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW264721731 BCX8\"><strong> :<\/strong> Nous pouvons partager Vos informations personnelles avec des Fournisseurs de services pour surveiller et analyser l&#8217;utilisation de Notre service et pour Vous contacter.<\/span><\/span><span class=\"EOP SCXW264721731 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW89165389 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW89165389 BCX8\">Pour les transferts d&#8217;entreprise<\/span><\/span><\/strong><span class=\"TextRun SCXW89165389 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW89165389 BCX8\"><strong> :<\/strong> Nous pouvons partager ou transf\u00e9rer Vos informations personnelles en relation avec, ou pendant les n\u00e9gociations de, toute fusion, vente d&#8217;actifs de l\u2019Entreprise, financement ou acquisition de tout ou partie de Notre entreprise par une autre entreprise.<\/span><\/span><span class=\"EOP SCXW89165389 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW91567629 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW91567629 BCX8\">Avec des affili\u00e9s<\/span><\/span><\/strong><span class=\"TextRun SCXW91567629 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW91567629 BCX8\"><strong> :<\/strong> Nous pouvons partager Vos informations avec Nos affili\u00e9s. Le cas \u00e9ch\u00e9ant, Nous exigerons de ces affili\u00e9s qu&#8217;ils respectent cette Politique de confidentialit\u00e9. Les affili\u00e9s comprennent Notre soci\u00e9t\u00e9 m\u00e8re et toute autre filiale, partenaire de coentreprise ou autre entreprise que Nous contr\u00f4lons ou qui est sous notre contr\u00f4le commun.<\/span><\/span><span class=\"EOP SCXW91567629 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW242113425 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW242113425 BCX8\">Avec des partenaires commerciaux<\/span><\/span><\/strong><span class=\"TextRun SCXW242113425 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW242113425 BCX8\"><strong> :<\/strong> Nous pouvons partager Vos informations avec Nos partenaires commerciaux pour Vous offrir certains produits, services ou promotions.<\/span><\/span><span class=\"EOP SCXW242113425 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW46686775 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW46686775 BCX8\">Avec d&#8217;autres utilisateurs<\/span><\/span><\/strong><span class=\"TextRun SCXW46686775 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW46686775 BCX8\"><strong> :<\/strong> lorsque Vous partagez des informations personnelles ou interagissez dans les zones publiques avec d&#8217;autres utilisateurs, ces informations peuvent \u00eatre consult\u00e9es par tous les utilisateurs et peuvent \u00eatre distribu\u00e9es publiquement \u00e0 l&#8217;ext\u00e9rieur. Si Vous interagissez avec d&#8217;autres utilisateurs ou Vous inscrivez via un Service de m\u00e9dias sociaux tiers, Vos contacts sur le Service de m\u00e9dias sociaux tiers peuvent voir Votre nom, Votre profil, Vos photos et la description de Votre activit\u00e9. De m\u00eame, d&#8217;autres utilisateurs pourront voir les descriptions de Votre activit\u00e9, communiquer avec Vous et voir Votre profil.<\/span><\/span><span class=\"EOP SCXW46686775 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><strong><span class=\"TextRun Underlined SCXW210560614 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW210560614 BCX8\">Avec Votre consentement<\/span><\/span><\/strong><span class=\"TextRun SCXW210560614 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW210560614 BCX8\"><strong> :<\/strong> Nous pouvons divulguer Vos informations personnelles \u00e0 toute autre fin avec Votre consentement.<\/span><\/span><span class=\"EOP SCXW210560614 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35eb501 elementor-widget elementor-widget-heading\" data-id=\"35eb501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conservation de vos donn\u00e9es personnelles \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ffa048 elementor-widget elementor-widget-text-editor\" data-id=\"9ffa048\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">L\u2019Entreprise ne conservera Vos donn\u00e9es personnelles que pendant la dur\u00e9e n\u00e9cessaire aux fins \u00e9nonc\u00e9es dans la pr\u00e9sente Politique de confidentialit\u00e9. Nous conserverons et utiliserons Vos donn\u00e9es personnelles dans la mesure n\u00e9cessaire pour respecter Nos obligations l\u00e9gales (par exemple, si Nous sommes tenus de conserver Vos donn\u00e9es pour respecter les lois applicables), r\u00e9soudre les litiges et faire respecter Nos accords et politiques juridiques.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">L\u2019Entreprise conservera \u00e9galement les Donn\u00e9es d&#8217;utilisation \u00e0 des fins d&#8217;analyse interne. Les Donn\u00e9es d&#8217;utilisation sont g\u00e9n\u00e9ralement conserv\u00e9es pour une p\u00e9riode plus courte, sauf lorsque ces donn\u00e9es sont utilis\u00e9es pour renforcer la s\u00e9curit\u00e9 ou am\u00e9liorer la fonctionnalit\u00e9 de Notre Service, ou si Nous sommes l\u00e9galement oblig\u00e9s de conserver ces donn\u00e9es pendant des p\u00e9riodes plus longues.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e94dc61 elementor-widget elementor-widget-heading\" data-id=\"e94dc61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transfert de vos donn\u00e9es personnelles <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aefe750 elementor-widget elementor-widget-text-editor\" data-id=\"aefe750\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Vos informations, y compris Vos donn\u00e9es personnelles, sont trait\u00e9es dans les bureaux op\u00e9rationnels de l\u2019Entreprise et dans tout autre lieu o\u00f9 les parties impliqu\u00e9es dans le traitement sont situ\u00e9es. Cela signifie que ces informations peuvent \u00eatre transf\u00e9r\u00e9es &#8211; et conserv\u00e9es &#8211; sur des ordinateurs situ\u00e9s en dehors de Votre \u00c9tat, province, pays ou autre juridiction gouvernementale o\u00f9 les lois sur la protection des donn\u00e9es peuvent diff\u00e9rer de celles de Votre juridiction.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Votre consentement \u00e0 cette Politique de confidentialit\u00e9, suivi de Votre soumission de telles informations, repr\u00e9sente Votre accord \u00e0 ce transfert.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">L\u2019Entreprise prendra toutes les mesures raisonnablement n\u00e9cessaires pour s&#8217;assurer que Vos donn\u00e9es sont trait\u00e9es en toute s\u00e9curit\u00e9 et conform\u00e9ment \u00e0 cette Politique de confidentialit\u00e9 et aucun transfert de Vos donn\u00e9es personnelles ne sera effectu\u00e9 vers une organisation ou un pays, \u00e0 moins qu&#8217;il n&#8217;y ait des contr\u00f4les ad\u00e9quats en place, y compris concernant la s\u00e9curit\u00e9 de Vos donn\u00e9es et autres informations personnelles.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b473237 elementor-widget elementor-widget-heading\" data-id=\"b473237\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Divulgation de vos donn\u00e9es personnelles \n\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff32d96 elementor-widget elementor-widget-text-editor\" data-id=\"ff32d96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Business Transactions<\/strong><\/h3><p><span class=\"TextRun SCXW140663658 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW140663658 BCX8\">Si l\u2019Entreprise est impliqu\u00e9e dans une fusion, une acquisition ou une vente d&#8217;actifs, Vos donn\u00e9es personnelles peuvent \u00eatre transf\u00e9r\u00e9es. Nous Vous informerons avant que Vos donn\u00e9es personnelles ne soient transf\u00e9r\u00e9es et soumises \u00e0 une Politique de confidentialit\u00e9 diff\u00e9rente.<\/span><\/span><span class=\"EOP SCXW140663658 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><h3><span class=\"TextRun SCXW184993053 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW184993053 BCX8\" data-ccp-parastyle=\"heading 5\">Application de la loi<\/span><\/span><\/h3><p><span class=\"TextRun SCXW251453291 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW251453291 BCX8\">Dans certaines circonstances, l\u2019Entreprise peut \u00eatre tenue de divulguer Vos donn\u00e9es personnelles si elle est tenue de le faire par la loi ou en r\u00e9ponse \u00e0 des demandes valides des autorit\u00e9s publiques (par exemple, un tribunal ou une agence gouvernementale).<\/span><\/span><span class=\"EOP SCXW251453291 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><h3><span class=\"TextRun SCXW104470393 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW104470393 BCX8\" data-ccp-parastyle=\"heading 5\">Autres exigences l\u00e9gales<\/span><\/span><span class=\"EOP SCXW104470393 BCX8\" data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:80,&quot;335559740&quot;:276}\">\u00a0<\/span><\/h3><p><span class=\"TextRun SCXW116439982 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW116439982 BCX8\">L\u2019Entreprise peut divulguer Vos donn\u00e9es personnelles de bonne foi si une telle action est n\u00e9cessaire pour :<\/span><\/span><span class=\"EOP SCXW116439982 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><ul><li><span class=\"TextRun SCXW163804651 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW163804651 BCX8\">Se conformer \u00e0 une obligation l\u00e9gale<\/span><\/span><span class=\"EOP SCXW163804651 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span class=\"TextRun SCXW18855786 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW18855786 BCX8\">Prot\u00e9ger et d\u00e9fendre les droits ou les biens de l\u2019Entreprise<\/span><\/span><span class=\"EOP SCXW18855786 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span class=\"TextRun SCXW183370782 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW183370782 BCX8\">Pr\u00e9venir ou enqu\u00eater sur une \u00e9ventuelle fraude en relation avec le Service<\/span><\/span><span class=\"EOP SCXW183370782 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span class=\"TextRun SCXW135532681 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW135532681 BCX8\">Prot\u00e9ger la s\u00e9curit\u00e9 personnelle des utilisateurs du Service ou du public<\/span><\/span><span class=\"EOP SCXW135532681 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span class=\"TextRun SCXW245871288 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW245871288 BCX8\">e prot\u00e9ger contre la responsabilit\u00e9 l\u00e9gale<\/span><\/span><span class=\"EOP SCXW245871288 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ul><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3c2bb elementor-widget elementor-widget-heading\" data-id=\"6d3c2bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S\u00e9curit\u00e9 de vos donn\u00e9es personnelles \n\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91d1089 elementor-widget elementor-widget-text-editor\" data-id=\"91d1089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW167121984 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW167121984 BCX8\">La s\u00e9curit\u00e9 de Vos donn\u00e9es personnelles est importante pour Nous, mais n&#8217;oubliez pas qu&#8217;aucune m\u00e9thode de transmission sur Internet ou de stockage \u00e9lectronique n&#8217;est s\u00fbre \u00e0 100 %. Bien que Nous nous efforcions d&#8217;utiliser des moyens commercialement acceptables pour prot\u00e9ger Vos donn\u00e9es personnelles, Nous ne pouvons garantir leur s\u00e9curit\u00e9 absolue.<\/span><\/span><span class=\"EOP SCXW167121984 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4973272 elementor-widget elementor-widget-heading\" data-id=\"4973272\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vie priv\u00e9e des enfants <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80cfb15 elementor-widget elementor-widget-text-editor\" data-id=\"80cfb15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Notre service ne s&#8217;adresse pas aux personnes de moins de 13 ans. Nous ne collectons d\u00e9lib\u00e9r\u00e9ment aucune information personnelle identifiable aupr\u00e8s de quiconque \u00e2g\u00e9 de moins de 13 ans. Si Vous \u00eates un parent ou un tuteur et que Vous savez que Votre enfant Nous a fourni des donn\u00e9es personnelles, veuillez Nous contacter. Si Nous constatons que Nous avons collect\u00e9 des donn\u00e9es personnelles aupr\u00e8s de quiconque \u00e2g\u00e9 de moins de 13 ans sans v\u00e9rification du consentement parental, Nous prendrons les mesures n\u00e9cessaires pour supprimer ces informations de Nos serveurs.<\/span><\/p><p><span class=\"TextRun SCXW214463621 BCX8\" lang=\"EN\" xml:lang=\"EN\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW214463621 BCX8\">Si Nous avons besoin de Nous appuyer sur le consentement en tant que base l\u00e9gale pour traiter Vos informations et que Votre pays exige le consentement d&#8217;un parent, Nous pouvons demander le consentement de Votre parent avant de collecter et d&#8217;utiliser ces informations.<\/span><\/span><span class=\"EOP SCXW214463621 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d42a0a elementor-widget elementor-widget-heading\" data-id=\"4d42a0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Liens vers d'autres sites Web \n\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6abf5b elementor-widget elementor-widget-text-editor\" data-id=\"e6abf5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Notre Service peut contenir des liens vers d&#8217;autres sites Web qui ne sont pas exploit\u00e9s par Nous. Si Vous cliquez sur un lien tiers, Vous serez dirig\u00e9 vers le site de ce tiers. Nous Vous conseillons vivement de consulter la Politique de confidentialit\u00e9 de chaque site que Vous visitez.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous n&#8217;avons aucun contr\u00f4le sur le contenu, les politiques de confidentialit\u00e9 ou les pratiques des sites ou de services tiers.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d209266 elementor-widget elementor-widget-heading\" data-id=\"d209266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Changements apport\u00e9s \u00e0 cette Politique de confidentialit\u00e9 \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0ccab3 elementor-widget elementor-widget-text-editor\" data-id=\"e0ccab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Nous pouvons \u00eatre amen\u00e9s \u00e0 mettre \u00e0 jour Notre Politique de confidentialit\u00e9. Le cas \u00e9ch\u00e9ant, Nous Vous informerons de tout changement en publiant la nouvelle Politique de confidentialit\u00e9 sur cette page.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Nous Vous informerons par e-mail et\/ou par une notification importante sur notre Service, avant que le changement ne prenne effet et Nous mettrons \u00e0 jour la date de \u00ab Derni\u00e8re mise \u00e0 jour \u00bb en haut de cette Politique de confidentialit\u00e9.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Il est conseill\u00e9 de consulter r\u00e9guli\u00e8rement cette Politique de confidentialit\u00e9 pour tout changement. Les changements apport\u00e9s \u00e0 cette Politique de confidentialit\u00e9 sont effectifs lorsqu&#8217;ils sont publi\u00e9s sur cette page.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71e3409 elementor-widget elementor-widget-heading\" data-id=\"71e3409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nous contacter \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f5a50 elementor-widget elementor-widget-text-editor\" data-id=\"a2f5a50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Si Vous avez des questions sur cette Politique de confidentialit\u00e9, Vous pouvez Nous contacter :<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Par e-mail : office@remcogroup.ca<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Privacy Privacy Policy Politique de confidentialit\u00e9\u00a0 Remco Construcci\u00f3n Inc. Derni\u00e8re mise \u00e0 jour : 23\/06\/2023\u00a0 Veuillez lire attentivement cette Politique de confidentialit\u00e9 avant d&#8217;utiliser Notre Service. Les informations suivantes sont divulgu\u00e9es par Remco Construction Inc \u00e0 Votre \u00e9gard conform\u00e9ment \u00e0 la loi de Nouveau-Brunswick du Canada.\u00a0 Ce Site Web est exploit\u00e9 par Remco Construction Inc. &hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_header_footer","meta":{"_acf_changed":false,"_genesis_block_theme_hide_title":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry","post","without-featured-image"],"acf":[],"_links":{"self":[{"href":"https:\/\/buildremco.ca\/fr\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/buildremco.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/buildremco.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/buildremco.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buildremco.ca\/fr\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/buildremco.ca\/fr\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/buildremco.ca\/fr\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}